{"id":729,"date":"2023-07-05T16:19:36","date_gmt":"2023-07-05T19:19:36","guid":{"rendered":"https:\/\/www.osecac.org.ar\/Novedades\/?p=729"},"modified":"2023-07-13T16:09:43","modified_gmt":"2023-07-13T19:09:43","slug":"ya-esta-disponible-el-chequeo-preventivo-para-adultos","status":"publish","type":"post","link":"https:\/\/www.osecac.org.ar\/Novedades\/ya-esta-disponible-el-chequeo-preventivo-para-adultos\/","title":{"rendered":"\u00a1Ya est\u00e1 disponible el chequeo preventivo para adultos!"},"content":{"rendered":"\n[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.19.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb|0px||0px|false|false\u00bb custom_padding=\u00bb8px|0px||0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.19.0&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb custom_margin=\u00bb0px|0px|0px|0px|false|false\u00bb custom_padding=\u00bb0px|0px|0px|0px|false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.19.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<p><span style=\"font-weight: 400;\">Desde la Obra Social de los Empleados de Comercio y Actividades Civiles nos enorgullece anunciar que, a partir de este mes, nuestros\/as beneficiarios\/as mayores de 50 a\u00f1os podr\u00e1n solicitar el nuevo <\/span><b>Chequeo de Salud Integral +50,<\/b><span style=\"font-weight: 400;\"> un nuevo m\u00f3dulo m\u00e9dico dise\u00f1ado y adaptado a las necesidades espec\u00edficas de salud de este grupo etario.\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El programa apunta a fomentar la prevenci\u00f3n y el cuidado entre nuestros\/as afiliados\/as, dando un salto de calidad en lo que respecta a la atenci\u00f3n, ya que permite poder realizar todos los estudios en un mismo d\u00eda y lugar, y obtener luego de una semana, en una segunda consulta, la devoluci\u00f3n de los resultados obtenidos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dicho chequeo <\/span><b>incluye consultas cl\u00ednica, dermatol\u00f3gica, traumatol\u00f3gica y <\/b><span style=\"font-weight: 400;\">pr\u00e1cticas como<\/span><b> ecodoppler card\u00edaco y de vasos de cuello, electrocardiograma, laboratorio, estudios radiol\u00f3gicos y ecograf\u00eda abdominal. <\/b><span style=\"font-weight: 400;\">Para los\/as beneficiarios\/as de 50 a 65 a\u00f1os, tendr\u00e1n disponible tambi\u00e9n, una ergometr\u00eda para completar el apto f\u00edsico.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se puede <\/span><b>solicitar turno <\/b><span style=\"font-weight: 400;\">para el Chequeo Preventivo a trav\u00e9s de nuestra central telef\u00f3nica al<\/span><b> 0810-999-0101<\/b><span style=\"font-weight: 400;\"> donde se le indicar\u00e1 qu\u00e9 d\u00eda acudir a una primera consulta en el <\/span><b>Anexo del Sagrado Coraz\u00f3n<\/b><span style=\"font-weight: 400;\">, ubicado en la calle Bartolom\u00e9 Mitre 2135, para realizarse todos los ex\u00e1menes y, tambi\u00e9n, la fecha de la segunda consulta para que un profesional eval\u00fae los resultados de los mismos. Cabe destacar que esta segunda consulta, ser\u00e1 virtual para aquellos\/as beneficiarios\/as de 50 a 65 a\u00f1os y presencial para quienes tengan m\u00e1s de 65 a\u00f1os.<\/span><\/p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb text_orientation=\u00bbcenter\u00bb border_color_all=\u00bb#0D5AAA\u00bb border_width_all=\u00bb1px\u00bb custom_padding=\u00bb8px||||false|false\u00bb border_radii=\u00bbon|56px|56px|56px|56px\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<h4><span style=\"font-weight: 400;\">Servicio habilitado para beneficiarios\/as directos\/as de AMBA.\u00a0<\/span><\/h4>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb theme_builder_area=\u00bbpost_content\u00bb hover_enabled=\u00bb0&#8243; sticky_enabled=\u00bb0&#8243;]<p><strong>OSECAC m\u00e1s servicios, m\u00e1s salud.\u00a0<\/strong><\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n","protected":false},"excerpt":{"rendered":"<p>Desde la Obra Social de los Empleados de Comercio y Actividades Civiles nos enorgullece anunciar que, a partir de este mes, nuestros\/as beneficiarios\/as mayores de 50 a\u00f1os podr\u00e1n solicitar el nuevo Chequeo de Salud Integral +50, un nuevo m\u00f3dulo m\u00e9dico dise\u00f1ado y adaptado a las necesidades espec\u00edficas de salud de este grupo etario.\u00a0\u00a0\u00a0 El programa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":730,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[23],"tags":[],"class_list":["post-729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prevencion"],"_links":{"self":[{"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/posts\/729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/comments?post=729"}],"version-history":[{"count":0,"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/posts\/729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/media\/730"}],"wp:attachment":[{"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/media?parent=729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/categories?post=729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.osecac.org.ar\/Novedades\/wp-json\/wp\/v2\/tags?post=729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}